{"id":71026,"date":"2020-02-14T15:48:41","date_gmt":"2020-02-14T21:48:41","guid":{"rendered":"http:\/\/sateliteonline.mx\/web\/?p=71026"},"modified":"2020-02-14T15:48:41","modified_gmt":"2020-02-14T21:48:41","slug":"elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad","status":"publish","type":"post","link":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/","title":{"rendered":"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad"},"content":{"rendered":"<p>La importancia de la estimulaci\u00f3n temprana es tal que se considera un requisito b\u00e1sico para el \u00f3ptimo desarrollo del cerebro del beb\u00e9, ya que potencia sus funciones cerebrales en los aspectos cognitivo, ling\u00fc\u00edstico, motor y social, expres\u00f3 Gerardo Reyes Mariscal.<\/p>\n<p>El coordinador del \u00c1rea de Activaci\u00f3n F\u00edsica y Conexiones Cerebrales de la Facultad de Educaci\u00f3n F\u00edsica y Deporte de la Universidad Aut\u00f3noma de Sinaloa (UAS) destac\u00f3 que nuestro cerebro requiere informaci\u00f3n que le ayude a desarrollarse, por lo que su crecimiento depende de la cantidad, tipo y calidad de est\u00edmulos que recibe; puntualizando que las capacidades no se adquieren solo con el paso del tiempo.<\/p>\n<p>Ante esta actividad elemental que requieren los beb\u00e9s y ni\u00f1os, el docente universitario dio a conocer que a ra\u00edz de esto es que se est\u00e1 promoviendo en esta nueva \u00e1rea de la Facultad, Clases de Apoyo Psicomotriz y Estimulaci\u00f3n Temprana, las cuales buscan favorecer los movimientos de los infantes con el objetivo de motivar los sentidos a trav\u00e9s de sensaciones y relaciones entre el cuerpo y el exterior, mejorando su capacidad perceptiva por medio del movimiento y la respuesta corporal.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone  wp-image-71028\" src=\"http:\/\/sateliteonline.mx\/web\/wp-content\/uploads\/2020\/02\/thumbnail_GERARDO-REYES-2.jpg\" alt=\"\" width=\"408\" height=\"612\" \/><\/p>\n<p>\u201cEl ni\u00f1o a trav\u00e9s de las sensaciones, de la percepci\u00f3n y el conocimiento de su cuerpo va a convivir con el medio ambiente, con los objetos y va a encauzar las energ\u00edas en trabajar la coordinaci\u00f3n, su atenci\u00f3n, ahorita hay muchos ni\u00f1os con hiperactividad, \u00bfpor qu\u00e9? Porque se brincaron algunas de las etapas como podr\u00eda ser el arrastre, el gateo\u201d, detall\u00f3.<\/p>\n<p>Dio a conocer que estas clases de estimulaci\u00f3n est\u00e1n orientadas para beb\u00e9s desde los 45 d\u00edas de nacido, hasta ni\u00f1os de los 10 a\u00f1os, los cuales son atendidos por j\u00f3venes que est\u00e1n pr\u00f3ximos a egresar de la carrera de la Licenciatura en Educaci\u00f3n F\u00edsica, en un horario vespertino de 4:00 a 7:00.<\/p>\n<p>\u201cMejora lo que es el equilibrio, lo que es lo cognitivo, la convivencia con los dem\u00e1s compa\u00f1eros, eso va a mejorar el ni\u00f1o\u201d, indic\u00f3.<\/p>\n<p>Reyes Mariscal dio a conocer que el costo del servicio es de 400 pesos, donde el ni\u00f1o puede asistir tres veces a la semana a la terapia, la cual es de una hora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La importancia de la estimulaci\u00f3n temprana es tal que se considera un requisito b\u00e1sico para el \u00f3ptimo desarrollo<\/p>\n","protected":false},"author":3,"featured_media":71027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,4],"tags":[34131],"class_list":["post-71026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-titulares","tag-elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad - SateliteOnline.mx<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad - SateliteOnline.mx\" \/>\n<meta property=\"og:description\" content=\"La importancia de la estimulaci\u00f3n temprana es tal que se considera un requisito b\u00e1sico para el \u00f3ptimo desarrollo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/\" \/>\n<meta property=\"og:site_name\" content=\"SateliteOnline.mx\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-14T21:48:41+00:00\" \/>\n<meta name=\"author\" content=\"Mart\u00edn Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mart\u00edn Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/\"},\"author\":{\"name\":\"Mart\u00edn Garc\u00eda\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/63d682cf35ea089fff3322479ef092dc\"},\"headline\":\"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad\",\"datePublished\":\"2020-02-14T21:48:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/\"},\"wordCount\":398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad\"],\"articleSection\":[\"Local\",\"Titulares\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/\",\"name\":\"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad - SateliteOnline.mx\",\"isPartOf\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-02-14T21:48:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sateliteonline.mx\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#website\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/\",\"name\":\"SateliteOnline.mx\",\"description\":\"A la Vanguardia en Noticias\",\"publisher\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sateliteonline.mx\/wp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\",\"name\":\"SateliteOnline.mx\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png\",\"contentUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png\",\"width\":472,\"height\":181,\"caption\":\"SateliteOnline.mx\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/63d682cf35ea089fff3322479ef092dc\",\"name\":\"Mart\u00edn Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1f8a66211eb02bade2495282dbf9c4c2f41c1a6295a6761e720eb6ba6769082?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1f8a66211eb02bade2495282dbf9c4c2f41c1a6295a6761e720eb6ba6769082?s=96&d=mm&r=g\",\"caption\":\"Mart\u00edn Garc\u00eda\"},\"url\":\"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad - SateliteOnline.mx","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/","og_locale":"es_ES","og_type":"article","og_title":"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad - SateliteOnline.mx","og_description":"La importancia de la estimulaci\u00f3n temprana es tal que se considera un requisito b\u00e1sico para el \u00f3ptimo desarrollo","og_url":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/","og_site_name":"SateliteOnline.mx","article_published_time":"2020-02-14T21:48:41+00:00","author":"Mart\u00edn Garc\u00eda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mart\u00edn Garc\u00eda","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#article","isPartOf":{"@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/"},"author":{"name":"Mart\u00edn Garc\u00eda","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/63d682cf35ea089fff3322479ef092dc"},"headline":"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad","datePublished":"2020-02-14T21:48:41+00:00","mainEntityOfPage":{"@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/"},"wordCount":398,"commentCount":0,"publisher":{"@id":"https:\/\/sateliteonline.mx\/wp\/#organization"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#primaryimage"},"thumbnailUrl":"","keywords":["Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad"],"articleSection":["Local","Titulares"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/","url":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/","name":"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad - SateliteOnline.mx","isPartOf":{"@id":"https:\/\/sateliteonline.mx\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#primaryimage"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-02-14T21:48:41+00:00","breadcrumb":{"@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/sateliteonline.mx\/wp\/elemental-desarrollar-en-bebes-y-ninos-la-psicomotricidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sateliteonline.mx\/wp\/"},{"@type":"ListItem","position":2,"name":"Elemental desarrollar en beb\u00e9s y ni\u00f1os la psicomotricidad"}]},{"@type":"WebSite","@id":"https:\/\/sateliteonline.mx\/wp\/#website","url":"https:\/\/sateliteonline.mx\/wp\/","name":"SateliteOnline.mx","description":"A la Vanguardia en Noticias","publisher":{"@id":"https:\/\/sateliteonline.mx\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sateliteonline.mx\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sateliteonline.mx\/wp\/#organization","name":"SateliteOnline.mx","url":"https:\/\/sateliteonline.mx\/wp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png","contentUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png","width":472,"height":181,"caption":"SateliteOnline.mx"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/63d682cf35ea089fff3322479ef092dc","name":"Mart\u00edn Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1f8a66211eb02bade2495282dbf9c4c2f41c1a6295a6761e720eb6ba6769082?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1f8a66211eb02bade2495282dbf9c4c2f41c1a6295a6761e720eb6ba6769082?s=96&d=mm&r=g","caption":"Mart\u00edn Garc\u00eda"},"url":"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia\/"}]}},"jetpack_featured_media_url":"","rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Mart\u00edn Garc\u00eda","author_link":"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia\/"},"rttpg_comment":15,"rttpg_category":"<a href=\"https:\/\/sateliteonline.mx\/wp\/category\/local\/\" rel=\"category tag\">Local<\/a> <a href=\"https:\/\/sateliteonline.mx\/wp\/category\/titulares\/\" rel=\"category tag\">Titulares<\/a>","rttpg_excerpt":"La importancia de la estimulaci\u00f3n temprana es tal que se considera un requisito b\u00e1sico para el \u00f3ptimo desarrollo","_links":{"self":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/71026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/comments?post=71026"}],"version-history":[{"count":0,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/71026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/media?parent=71026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/categories?post=71026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/tags?post=71026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<br />
<b>Notice</b>:  ob_end_flush(): Failed to send buffer of zlib output compression (0) in <b>/home/satelite/public_html/wp/wp-includes/functions.php</b> on line <b>5481</b><br />
