{"id":253680,"date":"2026-05-13T14:48:09","date_gmt":"2026-05-13T20:48:09","guid":{"rendered":"https:\/\/sateliteonline.mx\/wp\/?p=253680"},"modified":"2026-05-13T15:24:40","modified_gmt":"2026-05-13T21:24:40","slug":"reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza","status":"publish","type":"post","link":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/","title":{"rendered":"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>= Luego de la suspensi\u00f3n por \u201cD\u00eda de las Madres\u201d<\/p>\n\n\n\n<p>= El lider, Orioles de Navolato, contra la UAdeO<\/p>\n\n\n\n<p>= JAPAC, el anfitri\u00f3n, frente a Trucking<\/p>\n\n\n\n<p>= Y un duelazo: Strike Out versus Dodgers<\/p>\n\n\n\n<p>Jorge Luis Telles Salazar<\/p>\n\n\n\n<p>Tras la pausa del 10 de mayo -sencillamente obligada \u2013 el pr\u00f3ximo domingo se reanudan las hostilidades en lo que es todav\u00eda la primera vuelta de la temporada 2026 de liga JAPAC de beisbol de primera fuerza.<\/p>\n\n\n\n<p>Y obviamente el encuentro que m\u00e1s llama la atenci\u00f3n es el que sostendr\u00e1n los Orioles de Navolato frente a los Linces de la Universidad Aut\u00f3noma de Occidente, programado para las 10: 00 horas, en el campo Uno de la unidad deportiva de la empresa paramunicipal. Orioles es l\u00edder del grupo \u201cB,\u201d con marca de 5 victorias y una derrota y puntero general, por supuesto.<\/p>\n\n\n\n<p>Para este domingo, sin embargo, el compromiso no luce nada f\u00e1cil. Los Linces marchan con saldo parejo de 3-3 y es un equipo altamente competitivo. Lo suficiente para meter en problemas al team sensaci\u00f3n de la campa\u00f1a.<\/p>\n\n\n\n<p>Ah\u00ed mismo, solo que a las 2 de la tarde, Sinaloa Ci5 Harper chocar\u00e1 contra Rangers de GAPSA, seguramente en medio de un calor\u00f3n infernal. Hasta ahora, Sinaloa Ci5 camina con \u00b4paso firme a la calificaci\u00f3n a los \u201cpley offs\u201d y es, sin duda, uno de los que pasar\u00e1n lista de presente en la postemporada, al registrar marca de 4-3 en el grupo \u201cA\u201d. Los Rangers, por su parte, no han lucido lo que de ellos se esperaban y siguen en n\u00fameros rojos, con r\u00e9cord de 3-4, tambi\u00e9n en el \u201cA\u201d. Pinta para un buen juego. Lo ser\u00e1.<\/p>\n\n\n\n<p>En el campo Tres, un duelo prometedor, a las 14: 00 horas: Dodgers frente a Strike Out, ambos del grupo \u201cA\u201d. Dodgers marcha con n\u00fameros de 4-2 y Strike Out de 4-3. Ambos en la pelea por el liderato del sector y por asegurar la mayor cifra posible de puntos para una calificaci\u00f3n tranquila a los \u201cpley offs\u201d.<\/p>\n\n\n\n<p>En ese mismo campo, a las 10 de la ma\u00f1ana, los Astros de Lecani que ya tomaron ritmo ganador (4-3 en el bloque \u201cA\u201d), medir\u00e1n fuerzas con Taquer\u00eda San Mart\u00edn, equipo muy por debajo de la expectativa, pero que puede reaccionar en cualquier momento. Por lo pronto, con saldo de 2-4.<\/p>\n\n\n\n<p>Finalmente, en el campo Uno, los siguientes partidos:<\/p>\n\n\n\n<p>A las 14: 00 horas, el anfitri\u00f3n JAPAC (3-3 en el \u201cA\u201d) se las ver\u00e1 con Trucking (4-3 en el \u201cB\u201d). Los dos, con una sola consigna: sostenerse en la lucha por los primeros lugares.<\/p>\n\n\n\n<p>Y antes, a las 10: 00 horas, Camaroneros de LOCSA, van apenas por su primer triunfo, tras seis reveses al hilo, a partir del arranque de la campa\u00f1a. \u00bfLo permitir\u00e1 RALO\/UAS\/Comunicaci\u00f3n, con su r\u00e9cord de 3-4?<\/p>\n\n\n\n<p>Parece una buena programaci\u00f3n.<\/p>\n\n\n\n<p>Lo ser\u00e1.<\/p>\n\n\n\n<p>Y por all\u00e1 nos vemos.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>= Luego de la suspensi\u00f3n por \u201cD\u00eda de las Madres\u201d = El lider, Orioles de Navolato, contra la<\/p>\n","protected":false},"author":5,"featured_media":164588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[215],"tags":[],"class_list":["post-253680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-palco-premier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza - SateliteOnline.mx<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza - SateliteOnline.mx\" \/>\n<meta property=\"og:description\" content=\"= Luego de la suspensi\u00f3n por \u201cD\u00eda de las Madres\u201d = El lider, Orioles de Navolato, contra la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/\" \/>\n<meta property=\"og:site_name\" content=\"SateliteOnline.mx\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T20:48:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T21:24:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1085\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mart\u00edn Garc\u00eda Castillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mart\u00edn Garc\u00eda Castillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/\"},\"author\":{\"name\":\"Mart\u00edn Garc\u00eda Castillo\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf\"},\"headline\":\"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza\",\"datePublished\":\"2026-05-13T20:48:09+00:00\",\"dateModified\":\"2026-05-13T21:24:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/\"},\"wordCount\":497,\"publisher\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png\",\"articleSection\":[\"PALCO PREMIER | Jorge Luis Telles S.\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/\",\"name\":\"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza - SateliteOnline.mx\",\"isPartOf\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png\",\"datePublished\":\"2026-05-13T20:48:09+00:00\",\"dateModified\":\"2026-05-13T21:24:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#primaryimage\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png\",\"contentUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png\",\"width\":1085,\"height\":669},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sateliteonline.mx\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#website\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/\",\"name\":\"SateliteOnline.mx\",\"description\":\"A la Vanguardia en Noticias\",\"publisher\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sateliteonline.mx\/wp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\",\"name\":\"SateliteOnline.mx\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png\",\"contentUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png\",\"width\":472,\"height\":181,\"caption\":\"SateliteOnline.mx\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf\",\"name\":\"Mart\u00edn Garc\u00eda Castillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g\",\"caption\":\"Mart\u00edn Garc\u00eda Castillo\"},\"url\":\"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza - SateliteOnline.mx","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/","og_locale":"es_ES","og_type":"article","og_title":"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza - SateliteOnline.mx","og_description":"= Luego de la suspensi\u00f3n por \u201cD\u00eda de las Madres\u201d = El lider, Orioles de Navolato, contra la","og_url":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/","og_site_name":"SateliteOnline.mx","article_published_time":"2026-05-13T20:48:09+00:00","article_modified_time":"2026-05-13T21:24:40+00:00","og_image":[{"width":1085,"height":669,"url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png","type":"image\/png"}],"author":"Mart\u00edn Garc\u00eda Castillo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mart\u00edn Garc\u00eda Castillo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#article","isPartOf":{"@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/"},"author":{"name":"Mart\u00edn Garc\u00eda Castillo","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf"},"headline":"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza","datePublished":"2026-05-13T20:48:09+00:00","dateModified":"2026-05-13T21:24:40+00:00","mainEntityOfPage":{"@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/"},"wordCount":497,"publisher":{"@id":"https:\/\/sateliteonline.mx\/wp\/#organization"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#primaryimage"},"thumbnailUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png","articleSection":["PALCO PREMIER | Jorge Luis Telles S."],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/","url":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/","name":"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza - SateliteOnline.mx","isPartOf":{"@id":"https:\/\/sateliteonline.mx\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#primaryimage"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#primaryimage"},"thumbnailUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png","datePublished":"2026-05-13T20:48:09+00:00","dateModified":"2026-05-13T21:24:40+00:00","breadcrumb":{"@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#primaryimage","url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png","contentUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png","width":1085,"height":669},{"@type":"BreadcrumbList","@id":"https:\/\/sateliteonline.mx\/wp\/reanuda-actividades-la-liga-japac-de-beisbol-de-primera-fuerza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sateliteonline.mx\/wp\/"},{"@type":"ListItem","position":2,"name":"Reanuda actividades La liga JAPAC de Beisbol de Primera Fuerza"}]},{"@type":"WebSite","@id":"https:\/\/sateliteonline.mx\/wp\/#website","url":"https:\/\/sateliteonline.mx\/wp\/","name":"SateliteOnline.mx","description":"A la Vanguardia en Noticias","publisher":{"@id":"https:\/\/sateliteonline.mx\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sateliteonline.mx\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sateliteonline.mx\/wp\/#organization","name":"SateliteOnline.mx","url":"https:\/\/sateliteonline.mx\/wp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png","contentUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png","width":472,"height":181,"caption":"SateliteOnline.mx"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf","name":"Mart\u00edn Garc\u00eda Castillo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g","caption":"Mart\u00edn Garc\u00eda Castillo"},"url":"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia2\/"}]}},"jetpack_featured_media_url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png","rttpg_featured_image_url":{"full":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png",1085,669,false],"landscape":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png",1085,669,false],"portraits":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png",1085,669,false],"thumbnail":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2-150x150.png",150,150,true],"medium":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2-300x185.png",300,185,true],"large":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2-1024x631.png",640,394,true],"1536x1536":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png",1085,669,false],"2048x2048":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2.png",1085,669,false],"morenews-featured":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2-1024x631.png",1024,631,true],"morenews-large":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2-825x575.png",825,575,true],"morenews-medium":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2023\/10\/Palco-2-590x410.png",590,410,true]},"rttpg_author":{"display_name":"Mart\u00edn Garc\u00eda Castillo","author_link":"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia2\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/sateliteonline.mx\/wp\/category\/palco-premier\/\" rel=\"category tag\">PALCO PREMIER | Jorge Luis Telles S.<\/a>","rttpg_excerpt":"= Luego de la suspensi\u00f3n por \u201cD\u00eda de las Madres\u201d = El lider, Orioles de Navolato, contra la","_links":{"self":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/253680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/comments?post=253680"}],"version-history":[{"count":1,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/253680\/revisions"}],"predecessor-version":[{"id":253681,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/253680\/revisions\/253681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/media\/164588"}],"wp:attachment":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/media?parent=253680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/categories?post=253680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/tags?post=253680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<br />
<b>Notice</b>:  ob_end_flush(): Failed to send buffer of zlib output compression (0) in <b>/home/satelite/public_html/wp/wp-includes/functions.php</b> on line <b>5481</b><br />
