{"id":233826,"date":"2025-10-30T20:03:18","date_gmt":"2025-10-31T02:03:18","guid":{"rendered":"https:\/\/sateliteonline.mx\/wp\/?p=233826"},"modified":"2025-10-30T20:03:21","modified_gmt":"2025-10-31T02:03:21","slug":"culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente","status":"publish","type":"post","link":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/","title":{"rendered":"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente"},"content":{"rendered":"\n<p>Culiac\u00e1n, Sin., 30 de octubre de 2025. \u2014 La Central Mexicana de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, A.C., a trav\u00e9s del \u00c1rea Sinaloa I, anunci\u00f3 la realizaci\u00f3n de la 36\u00aa Reuni\u00f3n de Servicios Generales de la Regi\u00f3n Norte Poniente, que se llevar\u00e1 a cabo los d\u00edas 7, 8 y 9 de noviembre en el Polideportivo de la Universidad Aut\u00f3noma de Sinaloa (UAS).<\/p>\n\n\n\n<p>En rueda de prensa, se inform\u00f3 que este encuentro reunir\u00e1 a delegados, custodios, servidores y miembros de A.A., de los estados de Baja California, Baja California Sur, Chihuahua, Durango, Sonora y Sinaloa, con el prop\u00f3sito de fortalecer la unidad, compartir experiencias y analizar estrategias que permitan seguir llevando el mensaje de recuperaci\u00f3n a quienes enfrentan problemas con el alcohol.<\/p>\n\n\n\n<p>El evento contar\u00e1 con sesiones de trabajo, paneles de reflexi\u00f3n, actividades culturales y presentaciones informativas sobre el funcionamiento de los servicios generales de la organizaci\u00f3n, la importancia del anonimato y la cooperaci\u00f3n con la comunidad profesional y los medios de comunicaci\u00f3n.<\/p>\n\n\n\n<p>Durante su intervenci\u00f3n, la secretaria de Desarrollo Econ\u00f3mico del Ayuntamiento de Culiac\u00e1n, Janet Faviola Tostado Noriega, destac\u00f3 la relevancia de este encuentro para la ciudad:<\/p>\n\n\n\n<p>\u201cM\u00e1s all\u00e1 de ser un evento con un tema tan sensible, representa un voto de confianza hacia Culiac\u00e1n como ciudad anfitriona. Recibiremos con gusto a cerca de cuatro mil participantes provenientes de seis estados del pa\u00eds, lo que traer\u00e1 consigo una importante derrama econ\u00f3mica y una ocupaci\u00f3n hotelera de alrededor de 900 habitaciones\u201d, expres\u00f3.<\/p>\n\n\n\n<p>Tostado Noriega a\u00f1adi\u00f3 que el Ayuntamiento de Culiac\u00e1n se encuentra preparado para brindar apoyo a trav\u00e9s de las \u00e1reas de seguridad p\u00fablica, tr\u00e1nsito, salud y turismo, con el objetivo de garantizar el \u00e9xito del evento y la seguridad de los visitantes.<\/p>\n\n\n\n<p>\u201cCuliac\u00e1n est\u00e1 listo para recibirlos con calidez. Somos una ciudad de gente trabajadora, resiliente y solidaria. Queremos que los asistentes se lleven una buena impresi\u00f3n de nuestra tierra, de su hospitalidad, su comida y su fortaleza\u201d, enfatiz\u00f3.<\/p>\n\n\n\n<p>Alcoh\u00f3licos An\u00f3nimos reiter\u00f3 que no pertenece a ninguna religi\u00f3n, secta o instituci\u00f3n pol\u00edtica, y que su \u00fanico prop\u00f3sito es ayudar a las personas que enfrentan problemas con su manera de beber, ofreciendo esperanza, comprensi\u00f3n y un programa de recuperaci\u00f3n basado en principios espirituales y en la experiencia compartida de sus miembros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culiac\u00e1n, Sin., 30 de octubre de 2025. \u2014 La Central Mexicana de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, A.C.,<\/p>\n","protected":false},"author":5,"featured_media":233827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,4],"tags":[56854,56855],"class_list":["post-233826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-titulares","tag-culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos","tag-region-norte-poniente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente - SateliteOnline.mx<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente - SateliteOnline.mx\" \/>\n<meta property=\"og:description\" content=\"Culiac\u00e1n, Sin., 30 de octubre de 2025. \u2014 La Central Mexicana de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, A.C.,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/\" \/>\n<meta property=\"og:site_name\" content=\"SateliteOnline.mx\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-31T02:03:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T02:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mart\u00edn Garc\u00eda Castillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mart\u00edn Garc\u00eda Castillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/\"},\"author\":{\"name\":\"Mart\u00edn Garc\u00eda Castillo\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf\"},\"headline\":\"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente\",\"datePublished\":\"2025-10-31T02:03:18+00:00\",\"dateModified\":\"2025-10-31T02:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/\"},\"wordCount\":422,\"publisher\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg\",\"keywords\":[\"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos\",\"Regi\u00f3n Norte Poniente\"],\"articleSection\":[\"Local\",\"Titulares\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/\",\"name\":\"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente - SateliteOnline.mx\",\"isPartOf\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg\",\"datePublished\":\"2025-10-31T02:03:18+00:00\",\"dateModified\":\"2025-10-31T02:03:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#primaryimage\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg\",\"contentUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sateliteonline.mx\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#website\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/\",\"name\":\"SateliteOnline.mx\",\"description\":\"A la Vanguardia en Noticias\",\"publisher\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sateliteonline.mx\/wp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\",\"name\":\"SateliteOnline.mx\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png\",\"contentUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png\",\"width\":472,\"height\":181,\"caption\":\"SateliteOnline.mx\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf\",\"name\":\"Mart\u00edn Garc\u00eda Castillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g\",\"caption\":\"Mart\u00edn Garc\u00eda Castillo\"},\"url\":\"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente - SateliteOnline.mx","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/","og_locale":"es_ES","og_type":"article","og_title":"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente - SateliteOnline.mx","og_description":"Culiac\u00e1n, Sin., 30 de octubre de 2025. \u2014 La Central Mexicana de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, A.C.,","og_url":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/","og_site_name":"SateliteOnline.mx","article_published_time":"2025-10-31T02:03:18+00:00","article_modified_time":"2025-10-31T02:03:21+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg","type":"image\/jpeg"}],"author":"Mart\u00edn Garc\u00eda Castillo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mart\u00edn Garc\u00eda Castillo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#article","isPartOf":{"@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/"},"author":{"name":"Mart\u00edn Garc\u00eda Castillo","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf"},"headline":"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente","datePublished":"2025-10-31T02:03:18+00:00","dateModified":"2025-10-31T02:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/"},"wordCount":422,"publisher":{"@id":"https:\/\/sateliteonline.mx\/wp\/#organization"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#primaryimage"},"thumbnailUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg","keywords":["Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos","Regi\u00f3n Norte Poniente"],"articleSection":["Local","Titulares"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/","url":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/","name":"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente - SateliteOnline.mx","isPartOf":{"@id":"https:\/\/sateliteonline.mx\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#primaryimage"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#primaryimage"},"thumbnailUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg","datePublished":"2025-10-31T02:03:18+00:00","dateModified":"2025-10-31T02:03:21+00:00","breadcrumb":{"@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#primaryimage","url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg","contentUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/sateliteonline.mx\/wp\/culiacan-sera-sede-de-la-36a-reunion-de-servicios-generales-de-alcoholicos-anonimos-region-norte-poniente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sateliteonline.mx\/wp\/"},{"@type":"ListItem","position":2,"name":"Culiac\u00e1n ser\u00e1 sede de la 36\u00aa Reuni\u00f3n de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, Regi\u00f3n Norte Poniente"}]},{"@type":"WebSite","@id":"https:\/\/sateliteonline.mx\/wp\/#website","url":"https:\/\/sateliteonline.mx\/wp\/","name":"SateliteOnline.mx","description":"A la Vanguardia en Noticias","publisher":{"@id":"https:\/\/sateliteonline.mx\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sateliteonline.mx\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sateliteonline.mx\/wp\/#organization","name":"SateliteOnline.mx","url":"https:\/\/sateliteonline.mx\/wp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png","contentUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png","width":472,"height":181,"caption":"SateliteOnline.mx"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf","name":"Mart\u00edn Garc\u00eda Castillo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g","caption":"Mart\u00edn Garc\u00eda Castillo"},"url":"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia2\/"}]}},"jetpack_featured_media_url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg","rttpg_featured_image_url":{"full":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg",2560,1706,false],"landscape":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg",2560,1706,false],"portraits":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM.jpeg",2560,1706,false],"thumbnail":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM-150x150.jpeg",150,150,true],"medium":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM-300x200.jpeg",300,200,true],"large":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM-1024x682.jpeg",640,426,true],"1536x1536":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM-1536x1024.jpeg",1536,1024,true],"2048x2048":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM-2048x1365.jpeg",2048,1365,true],"morenews-featured":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM-1024x682.jpeg",1024,682,true],"morenews-large":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM-825x575.jpeg",825,575,true],"morenews-medium":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-30-at-12.46.35-PM-590x410.jpeg",590,410,true]},"rttpg_author":{"display_name":"Mart\u00edn Garc\u00eda Castillo","author_link":"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia2\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/sateliteonline.mx\/wp\/category\/local\/\" rel=\"category tag\">Local<\/a> <a href=\"https:\/\/sateliteonline.mx\/wp\/category\/titulares\/\" rel=\"category tag\">Titulares<\/a>","rttpg_excerpt":"Culiac\u00e1n, Sin., 30 de octubre de 2025. \u2014 La Central Mexicana de Servicios Generales de Alcoh\u00f3licos An\u00f3nimos, A.C.,","_links":{"self":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/233826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/comments?post=233826"}],"version-history":[{"count":1,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/233826\/revisions"}],"predecessor-version":[{"id":233828,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/233826\/revisions\/233828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/media\/233827"}],"wp:attachment":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/media?parent=233826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/categories?post=233826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/tags?post=233826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<br />
<b>Notice</b>:  ob_end_flush(): Failed to send buffer of zlib output compression (0) in <b>/home/satelite/public_html/wp/wp-includes/functions.php</b> on line <b>5481</b><br />
