{"id":233057,"date":"2025-10-24T00:47:13","date_gmt":"2025-10-24T06:47:13","guid":{"rendered":"https:\/\/sateliteonline.mx\/wp\/?p=233057"},"modified":"2025-10-24T00:47:15","modified_gmt":"2025-10-24T06:47:15","slug":"uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos","status":"publish","type":"post","link":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/","title":{"rendered":"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos"},"content":{"rendered":"\n<p><strong>El alcalde Juan de Dios G\u00e1mez Mend\u00edvil destac\u00f3 a la Universidad Aut\u00f3noma de Sinaloa como pilar del desarrollo cultural y acad\u00e9mico en la regi\u00f3n; 30 alumnos integran la primera generaci\u00f3n.<\/strong><\/p>\n\n\n\n<p>Culiac\u00e1n, Sinaloa.- Con la Universidad Aut\u00f3noma de Sinaloa (UAS) como sede y aliada estrat\u00e9gica, el alcalde de Culiac\u00e1n, Juan de Dios G\u00e1mez Mend\u00edvil, puso en marcha el primer <em>Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos<\/em>, una iniciativa conjunta entre el Ayuntamiento de Culiac\u00e1n, el Centro de Capacitaci\u00f3n Cinematogr\u00e1fica (CCC) de la Ciudad de M\u00e9xico, la Secretar\u00eda de Cultura y la propia UAS.<\/p>\n\n\n\n<p>El programa tiene como prop\u00f3sito impulsar la expresi\u00f3n cinematogr\u00e1fica, formar nuevos p\u00fablicos y promover el cine como herramienta cultural y social para la transmisi\u00f3n de valores y la construcci\u00f3n de una cultura de paz.<\/p>\n\n\n\n<p>Durante la inauguraci\u00f3n, realizada en la Facultad de Estudios Internacionales y Pol\u00edticas P\u00fablicas, el alcalde G\u00e1mez Mend\u00edvil resalt\u00f3 que este proyecto representa un paso significativo para incorporar la cultura y las artes dentro de la agenda p\u00fablica de su administraci\u00f3n.<\/p>\n\n\n\n<p>Agradeci\u00f3 al rector de la UAS, doctor Jes\u00fas Madue\u00f1a Molina, por el respaldo y la colaboraci\u00f3n institucional, al afirmar que la M\u00e1xima Casa de Estudios es un referente indispensable en el desarrollo acad\u00e9mico, art\u00edstico y cultural de Sinaloa.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"233059\" src=\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-3-1024x682.jpeg\" alt=\"\" class=\"wp-image-233059\" srcset=\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-3-1024x682.jpeg 1024w, https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-3-300x200.jpeg 300w, https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-3-768x512.jpeg 768w, https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-3-1536x1023.jpeg 1536w, https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-3.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"233058\" src=\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-5-1024x682.jpeg\" alt=\"\" class=\"wp-image-233058\" srcset=\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-5-1024x682.jpeg 1024w, https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-5-300x200.jpeg 300w, https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-5-768x512.jpeg 768w, https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-5-1536x1023.jpeg 1536w, https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-5.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>\u201cGracias a la universidad por ayudarnos a construir esto que para nosotros es un sue\u00f1o. Si queremos impulsar una cultura de cambio con nuevos valores, no se puede concebir sin la participaci\u00f3n de la comunidad universitaria, desde las preparatorias hasta las facultades\u201d, expres\u00f3 el alcalde.<\/p>\n\n\n\n<p>Por su parte, el director de la Facultad de Estudios Internacionales y Pol\u00edticas P\u00fablicas, doctor Yasser Orlando Espinoza Garc\u00eda, dio la bienvenida a los 30 estudiantes que integran la primera generaci\u00f3n del diplomado, invit\u00e1ndolos a aprovechar al m\u00e1ximo esta oportunidad de formaci\u00f3n.<\/p>\n\n\n\n<p>\u201cLas puertas de la Facultad y de la Universidad est\u00e1n abiertas para este tipo de proyectos que fortalecen la vida acad\u00e9mica y cultural\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Finalmente, el coordinador del diplomado y cineasta internacional C\u00e9sar Uriarte destac\u00f3 la calidad del proceso de selecci\u00f3n ante el alto n\u00famero de aspirantes y se mostr\u00f3 entusiasmado de iniciar esta primera edici\u00f3n, con el compromiso de seguir promoviendo el talento y la creatividad cinematogr\u00e1fica desde su ciudad natal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El alcalde Juan de Dios G\u00e1mez Mend\u00edvil destac\u00f3 a la Universidad Aut\u00f3noma de Sinaloa como pilar del desarrollo<\/p>\n","protected":false},"author":5,"featured_media":233060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[56610],"class_list":["post-233057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos - SateliteOnline.mx<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos - SateliteOnline.mx\" \/>\n<meta property=\"og:description\" content=\"El alcalde Juan de Dios G\u00e1mez Mend\u00edvil destac\u00f3 a la Universidad Aut\u00f3noma de Sinaloa como pilar del desarrollo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/\" \/>\n<meta property=\"og:site_name\" content=\"SateliteOnline.mx\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-24T06:47:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T06:47:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mart\u00edn Garc\u00eda Castillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mart\u00edn Garc\u00eda Castillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/\"},\"author\":{\"name\":\"Mart\u00edn Garc\u00eda Castillo\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf\"},\"headline\":\"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos\",\"datePublished\":\"2025-10-24T06:47:13+00:00\",\"dateModified\":\"2025-10-24T06:47:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/\"},\"wordCount\":433,\"publisher\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg\",\"keywords\":[\"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos\"],\"articleSection\":[\"Local\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/\",\"name\":\"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos - SateliteOnline.mx\",\"isPartOf\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg\",\"datePublished\":\"2025-10-24T06:47:13+00:00\",\"dateModified\":\"2025-10-24T06:47:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#primaryimage\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg\",\"contentUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sateliteonline.mx\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#website\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/\",\"name\":\"SateliteOnline.mx\",\"description\":\"A la Vanguardia en Noticias\",\"publisher\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sateliteonline.mx\/wp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#organization\",\"name\":\"SateliteOnline.mx\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png\",\"contentUrl\":\"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png\",\"width\":472,\"height\":181,\"caption\":\"SateliteOnline.mx\"},\"image\":{\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf\",\"name\":\"Mart\u00edn Garc\u00eda Castillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g\",\"caption\":\"Mart\u00edn Garc\u00eda Castillo\"},\"url\":\"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos - SateliteOnline.mx","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/","og_locale":"es_ES","og_type":"article","og_title":"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos - SateliteOnline.mx","og_description":"El alcalde Juan de Dios G\u00e1mez Mend\u00edvil destac\u00f3 a la Universidad Aut\u00f3noma de Sinaloa como pilar del desarrollo","og_url":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/","og_site_name":"SateliteOnline.mx","article_published_time":"2025-10-24T06:47:13+00:00","article_modified_time":"2025-10-24T06:47:15+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg","type":"image\/jpeg"}],"author":"Mart\u00edn Garc\u00eda Castillo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mart\u00edn Garc\u00eda Castillo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#article","isPartOf":{"@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/"},"author":{"name":"Mart\u00edn Garc\u00eda Castillo","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf"},"headline":"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos","datePublished":"2025-10-24T06:47:13+00:00","dateModified":"2025-10-24T06:47:15+00:00","mainEntityOfPage":{"@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/"},"wordCount":433,"publisher":{"@id":"https:\/\/sateliteonline.mx\/wp\/#organization"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#primaryimage"},"thumbnailUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg","keywords":["UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos"],"articleSection":["Local"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/","url":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/","name":"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos - SateliteOnline.mx","isPartOf":{"@id":"https:\/\/sateliteonline.mx\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#primaryimage"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#primaryimage"},"thumbnailUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg","datePublished":"2025-10-24T06:47:13+00:00","dateModified":"2025-10-24T06:47:15+00:00","breadcrumb":{"@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#primaryimage","url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg","contentUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/sateliteonline.mx\/wp\/uas-y-ayuntamiento-de-culiacan-inauguran-el-primer-diplomado-en-creacion-de-proyectos-cinematograficos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sateliteonline.mx\/wp\/"},{"@type":"ListItem","position":2,"name":"UAS y Ayuntamiento de Culiac\u00e1n inauguran el primer Diplomado en Creaci\u00f3n de Proyectos Cinematogr\u00e1ficos"}]},{"@type":"WebSite","@id":"https:\/\/sateliteonline.mx\/wp\/#website","url":"https:\/\/sateliteonline.mx\/wp\/","name":"SateliteOnline.mx","description":"A la Vanguardia en Noticias","publisher":{"@id":"https:\/\/sateliteonline.mx\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sateliteonline.mx\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sateliteonline.mx\/wp\/#organization","name":"SateliteOnline.mx","url":"https:\/\/sateliteonline.mx\/wp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png","contentUrl":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/08\/cropped-LogoMX.png","width":472,"height":181,"caption":"SateliteOnline.mx"},"image":{"@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/921db88ec881d6570363ffc2cbea1cbf","name":"Mart\u00edn Garc\u00eda Castillo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sateliteonline.mx\/wp\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98c57e8d915e8b37410f3b581119554d00f595ff779c8e69de376f9405a90fc6?s=96&d=mm&r=g","caption":"Mart\u00edn Garc\u00eda Castillo"},"url":"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia2\/"}]}},"jetpack_featured_media_url":"https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg","rttpg_featured_image_url":{"full":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg",1600,1066,false],"landscape":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg",1600,1066,false],"portraits":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg",1600,1066,false],"thumbnail":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4-150x150.jpeg",150,150,true],"medium":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4-300x200.jpeg",300,200,true],"large":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4-1024x682.jpeg",640,426,true],"1536x1536":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4-1536x1023.jpeg",1536,1023,true],"2048x2048":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4.jpeg",1600,1066,false],"morenews-featured":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4-1024x682.jpeg",1024,682,true],"morenews-large":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4-825x575.jpeg",825,575,true],"morenews-medium":["https:\/\/sateliteonline.mx\/wp\/wp-content\/uploads\/2025\/10\/DIPLOMADO-ALCALDE-4-590x410.jpeg",590,410,true]},"rttpg_author":{"display_name":"Mart\u00edn Garc\u00eda Castillo","author_link":"https:\/\/sateliteonline.mx\/wp\/author\/martingarcia2\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/sateliteonline.mx\/wp\/category\/local\/\" rel=\"category tag\">Local<\/a>","rttpg_excerpt":"El alcalde Juan de Dios G\u00e1mez Mend\u00edvil destac\u00f3 a la Universidad Aut\u00f3noma de Sinaloa como pilar del desarrollo","_links":{"self":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/233057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/comments?post=233057"}],"version-history":[{"count":1,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/233057\/revisions"}],"predecessor-version":[{"id":233061,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/posts\/233057\/revisions\/233061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/media\/233060"}],"wp:attachment":[{"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/media?parent=233057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/categories?post=233057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sateliteonline.mx\/wp\/wp-json\/wp\/v2\/tags?post=233057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<br />
<b>Notice</b>:  ob_end_flush(): Failed to send buffer of zlib output compression (0) in <b>/home/satelite/public_html/wp/wp-includes/functions.php</b> on line <b>5481</b><br />
